{"id":365,"date":"2023-05-30T18:01:42","date_gmt":"2023-05-30T10:01:42","guid":{"rendered":"http:\/\/www.zenith-vn.com\/?p=365"},"modified":"2024-04-12T11:17:55","modified_gmt":"2024-04-12T03:17:55","slug":"n-acetyl-l-tyrosine","status":"publish","type":"post","link":"https:\/\/www.zenith-vn.com\/vi\/n-axetyl-l-tyrosin\/","title":{"rendered":"N-axetyl-L-Tyrosine"},"content":{"rendered":"<figure class=\"wp-block-table\" style=\"font-size:16px\"><table class=\"has-text-color\" style=\"color:#666666\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">V\u1ebb b\u1ec1 ngo\u00e0i<\/td><td class=\"has-text-align-center\" data-align=\"center\">B\u1ed9t tinh th\u1ec3 m\u00e0u tr\u1eafng ho\u1eb7c g\u1ea7n nh\u01b0 tr\u1eafng ho\u1eb7c tinh th\u1ec3 kh\u00f4ng m\u00e0u<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">S\u1ef1 xu\u1ea5t hi\u1ec7n c\u1ee7a gi\u1ea3i ph\u00e1p<\/td><td class=\"has-text-align-center\" data-align=\"center\">R\u00f5 r\u00e0ng v\u00e0 kh\u00f4ng m\u00e0u<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">V\u00f2ng quay c\u1ee5 th\u1ec3<\/td><td class=\"has-text-align-center\" data-align=\"center\">+46\u00b0~+49\u00b0<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\">Nh\u1eefng ch\u1ea5t li\u00ean quan:<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Tyrosine<\/td><td class=\"has-text-align-center\" data-align=\"center\">.80.8%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">B\u1ea5t k\u1ef3 t\u1ea1p ch\u1ea5t kh\u00f4ng x\u00e1c \u0111\u1ecbnh<\/td><td class=\"has-text-align-center\" data-align=\"center\">.10%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u1ed5ng t\u1ea1p ch\u1ea5t<\/td><td class=\"has-text-align-center\" data-align=\"center\">.0%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">clorua<\/td><td class=\"has-text-align-center\" data-align=\"center\">.02%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">sunfat<\/td><td class=\"has-text-align-center\" data-align=\"center\">.02%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Amoni<\/td><td class=\"has-text-align-center\" data-align=\"center\">.02%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">S\u1eaft<\/td><td class=\"has-text-align-center\" data-align=\"center\">20ppm<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Kim lo\u1ea1i n\u1eb7ng<\/td><td class=\"has-text-align-center\" data-align=\"center\">10ppm<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">T\u1ed5n th\u1ea5t khi s\u1ea5y<\/td><td class=\"has-text-align-center\" data-align=\"center\">.50,5%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">D\u01b0 l\u01b0\u1ee3ng khi \u0111\u00e1nh l\u1eeda<\/td><td class=\"has-text-align-center\" data-align=\"center\">.110,1%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">x\u00e9t nghi\u1ec7m<\/td><td class=\"has-text-align-center\" data-align=\"center\">98.5-101.0%<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">N\u1ed9i \u0111\u1ed9c t\u1ed1 vi khu\u1ea9n<\/td><td class=\"has-text-align-center\" data-align=\"center\">&lt;25 IU\/g<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">C\u1ea4U TR\u00daC PH\u00c2N T\u1eec:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"162\" height=\"139\" src=\"http:\/\/www.zenith-vn.com\/wp-content\/uploads\/2023\/05\/20220427112334910.webp\" alt=\"\" class=\"wp-image-388\" title=\"\u56fe\u72471.png\" srcset=\"https:\/\/lingjuimg.com\/wp-content\/uploads\/huaanyn\/2023\/05\/20220427112334910.webp 162w, https:\/\/lingjuimg.com\/wp-content\/uploads\/huaanyn\/2023\/05\/20220427112334910-14x12.webp 14w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">C\u00f4ng th\u1ee9c ph\u00e2n t\u1eed:C<sub>11<\/sub>H<sub>13<\/sub>KH\u00d4NG<sub>4<\/sub><\/p>","protected":false},"excerpt":{"rendered":"<p>Appearance White or almost white, crystalline powder or colorless crystals Appearance of solution Clear &nbsp; and colorless Specific rotation +46\u00b0~+49\u00b0 Related substances: Tyrosine \u22640.8% Any unspecified impurity \u22640.10% Total impurities \u22641.0% Chloride \u22640.02% Sulfates \u22640.02% Ammonium \u22640.02% Iron \u226420ppm Heavy metals \u226410ppm Loss on drying \u22640.5% Residue on ignition \u22640.1% Assay 98.5-101.0% Bacterial endotoxins &lt;25 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-365","post","type-post","status-publish","format-standard","hentry","category-nutrition-ingredients"],"_links":{"self":[{"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/posts\/365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/comments?post=365"}],"version-history":[{"count":2,"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/posts\/365\/revisions"}],"predecessor-version":[{"id":389,"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/posts\/365\/revisions\/389"}],"wp:attachment":[{"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/media?parent=365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/categories?post=365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zenith-vn.com\/vi\/wp-json\/wp\/v2\/tags?post=365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}